{"id":6,"count":2,"description":"","link":"https:\/\/delphimasters.com.br\/blog\/tag\/threaddelphi\/","name":"threaddelphi","slug":"threaddelphi","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de threaddelphi - Delphi Masters-BLOG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/delphimasters.com.br\/blog\/tag\/threaddelphi\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de threaddelphi - Delphi Masters-BLOG\" \/>\n<meta property=\"og:url\" content=\"https:\/\/delphimasters.com.br\/blog\/tag\/threaddelphi\/\" \/>\n<meta property=\"og:site_name\" content=\"Delphi Masters-BLOG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/delphimasters.com.br\\\/blog\\\/tag\\\/threaddelphi\\\/\",\"url\":\"https:\\\/\\\/delphimasters.com.br\\\/blog\\\/tag\\\/threaddelphi\\\/\",\"name\":\"Arquivo de threaddelphi - Delphi Masters-BLOG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/delphimasters.com.br\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/delphimasters.com.br\\\/blog\\\/tag\\\/threaddelphi\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/delphimasters.com.br\\\/blog\\\/tag\\\/threaddelphi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/delphimasters.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"threaddelphi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/delphimasters.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/delphimasters.com.br\\\/blog\\\/\",\"name\":\"BLOG DelphiMasters\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/delphimasters.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/delphimasters.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/delphimasters.com.br\\\/blog\\\/#organization\",\"name\":\"BLOG DelphiMasters\",\"url\":\"https:\\\/\\\/delphimasters.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/delphimasters.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/delphimasters.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Delphi-Masters.png\",\"contentUrl\":\"https:\\\/\\\/delphimasters.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Delphi-Masters.png\",\"width\":1024,\"height\":1024,\"caption\":\"BLOG DelphiMasters\"},\"image\":{\"@id\":\"https:\\\/\\\/delphimasters.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/delphimasters\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de threaddelphi - Delphi Masters-BLOG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/delphimasters.com.br\/blog\/tag\/threaddelphi\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de threaddelphi - Delphi Masters-BLOG","og_url":"https:\/\/delphimasters.com.br\/blog\/tag\/threaddelphi\/","og_site_name":"Delphi Masters-BLOG","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/delphimasters.com.br\/blog\/tag\/threaddelphi\/","url":"https:\/\/delphimasters.com.br\/blog\/tag\/threaddelphi\/","name":"Arquivo de threaddelphi - Delphi Masters-BLOG","isPartOf":{"@id":"https:\/\/delphimasters.com.br\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/delphimasters.com.br\/blog\/tag\/threaddelphi\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/delphimasters.com.br\/blog\/tag\/threaddelphi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/delphimasters.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"threaddelphi"}]},{"@type":"WebSite","@id":"https:\/\/delphimasters.com.br\/blog\/#website","url":"https:\/\/delphimasters.com.br\/blog\/","name":"BLOG DelphiMasters","description":"","publisher":{"@id":"https:\/\/delphimasters.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/delphimasters.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/delphimasters.com.br\/blog\/#organization","name":"BLOG DelphiMasters","url":"https:\/\/delphimasters.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/delphimasters.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/delphimasters.com.br\/blog\/wp-content\/uploads\/2025\/07\/Delphi-Masters.png","contentUrl":"https:\/\/delphimasters.com.br\/blog\/wp-content\/uploads\/2025\/07\/Delphi-Masters.png","width":1024,"height":1024,"caption":"BLOG DelphiMasters"},"image":{"@id":"https:\/\/delphimasters.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/delphimasters\/"]}]}},"_links":{"self":[{"href":"https:\/\/delphimasters.com.br\/blog\/wp-json\/wp\/v2\/tags\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delphimasters.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/delphimasters.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/delphimasters.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}